{"id":355,"date":"2016-11-01T12:11:42","date_gmt":"2016-11-01T16:11:42","guid":{"rendered":"https:\/\/cecas.clemson.edu\/~avahidi\/wp-content\/uploads\/2016\/11\/Tejas.jpg"},"modified":"2016-11-01T15:05:45","modified_gmt":"2016-11-01T19:05:45","slug":"tejas-2","status":"inherit","type":"attachment","link":"https:\/\/cecas.clemson.edu\/~avahidi\/students\/tejas-2\/","title":{"rendered":"tejas"},"author":10,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-355","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/cecas.clemson.edu\/~avahidi\/wp-content\/uploads\/2016\/11\/Tejas.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"165\" src=\"https:\/\/cecas.clemson.edu\/~avahidi\/wp-content\/uploads\/2016\/11\/Tejas.jpg\" class=\"attachment-medium size-medium\" alt=\"\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":128,"height":165,"file":"2016\/11\/Tejas.jpg","sizes":{"thumbnail":{"file":"Tejas-128x150.jpg","width":128,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/cecas.clemson.edu\/~avahidi\/wp-content\/uploads\/2016\/11\/Tejas-128x150.jpg"},"full":{"file":"Tejas.jpg","width":128,"height":165,"mime_type":"image\/jpeg","source_url":"https:\/\/cecas.clemson.edu\/~avahidi\/wp-content\/uploads\/2016\/11\/Tejas.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":58,"source_url":"https:\/\/cecas.clemson.edu\/~avahidi\/wp-content\/uploads\/2016\/11\/Tejas.jpg","_links":{"self":[{"href":"https:\/\/cecas.clemson.edu\/~avahidi\/wp-json\/wp\/v2\/media\/355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cecas.clemson.edu\/~avahidi\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/cecas.clemson.edu\/~avahidi\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/cecas.clemson.edu\/~avahidi\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/cecas.clemson.edu\/~avahidi\/wp-json\/wp\/v2\/comments?post=355"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":58,"href":"https:\/\/cecas.clemson.edu\/~avahidi\/wp-json\/wp\/v2\/pages\/58"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}